{"id":110,"date":"2020-11-10T10:43:53","date_gmt":"2020-11-10T10:43:53","guid":{"rendered":"https:\/\/picockpit.com\/raspberry-pi\/?p=110"},"modified":"2023-08-30T11:04:30","modified_gmt":"2023-08-30T11:04:30","slug":"raspberry-pi-os-overview","status":"publish","type":"post","link":"https:\/\/picockpit.com\/raspberry-pi\/fr\/apercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi\/","title":{"rendered":"Aper\u00e7u du syst\u00e8me d'exploitation de Raspberry Pi"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Syst\u00e8mes d'exploitation pour tous les cas d'utilisation de Raspi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un syst\u00e8me d'exploitation Raspberry Pi pour tous : le Pi prend en charge de nombreux syst\u00e8mes d'exploitation diff\u00e9rents. Dans cet article, vous aurez une vue d'ensemble des syst\u00e8mes d'exploitation populaires pour le Raspi, et vous saurez quel syst\u00e8me d'exploitation vous devriez choisir pour votre projet \/ cas d'utilisation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les d\u00e9butants et la plupart des cas d'utilisation <strong><a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> <\/strong>(anciennement appel\u00e9 Raspbian) est un bon choix. Cliquez sur les boutons ci-dessous pour acc\u00e9der rapidement au syst\u00e8me d'exploitation qui vous int\u00e9resse, ou lisez la suite pour une introduction. <\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#libreelec\">LibreELEC<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#noobs\">NOOBS<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#windows10coreiot\">Windows 10 Core IoT<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#osmc\">OSMC<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#recalbox\">Recalbox<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#lakka\">Lakka<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#riscos\">RISC OS<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#screenlyose\">Screenly OSE<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#tlxos\">TLXOS<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#alpine\">Linux alpin<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"#suse\">SuSE Linux<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qu'est-ce qu'un syst\u00e8me d'exploitation sur le Raspberry Pi ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons d\u00e9j\u00e0 \u00e9crit sur <a href=\"https:\/\/picockpit.com\/raspberry-pi\/what-is-a-raspberry-pi-and-what-can-i-do-with-it\/\">ce qu'est un Raspberry Pi<\/a>. Le Raspberry Pi a besoin d'un syst\u00e8me d'exploitation (ou OS en abr\u00e9g\u00e9) pour fonctionner. Qu'est-ce qu'un syst\u00e8me d'exploitation ? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque ordinateur ex\u00e9cute du code. Pour permettre aux programmeurs de se concentrer sur les fonctions qu'ils ajoutent et de b\u00e9n\u00e9ficier d'une infrastructure commune, certains d\u00e9veloppeurs de logiciels et entreprises\/communaut\u00e9s se sont sp\u00e9cialis\u00e9s dans le d\u00e9veloppement d'une base logicielle sur laquelle tous les autres logiciels peuvent travailler. Cette base est appel\u00e9e syst\u00e8me d'exploitation. Il fournit toute la plomberie, les connexions et les param\u00e8tres n\u00e9cessaires pour permettre \u00e0 toutes les autres applications d'effectuer leur travail quotidien. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, vous pouvez utiliser Google Chrome pour naviguer sur le web, consulter des pages web, faire des achats en ligne, vous connecter avec vos amis via Facebook, etc. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Google Chrome a besoin d'un moyen pour vous afficher ces informations - il communique avec le syst\u00e8me d'exploitation (Raspberry Pi OS, qui est une variante de Debian - nous y reviendrons) pour vous les afficher (pour savoir quel \u00e9cran, quelle r\u00e9solution, etc.). Il doit \u00e9galement prendre en compte les donn\u00e9es de l'utilisateur (mouvements de la souris, saisie au clavier). Enfin, il doit acc\u00e9der \u00e0 certains fichiers du syst\u00e8me - fichiers de cache, etc. Les <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi <\/a>(anciennement appel\u00e9 Raspbian) prend en charge toutes ces fonctions, Chrome peut simplement \"appeler\" le code du syst\u00e8me d'exploitation pour traiter ce dont il a besoin, au lieu d'avoir du code pour tout. D'autres applications peuvent b\u00e9n\u00e9ficier du m\u00eame code.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L'environnement de bureau fait partie du syst\u00e8me d'exploitation - la partie visible. Mais il se passe bien d'autres choses sous le capot. (Et <a href=\"https:\/\/picockpit.com\">PiCockpit <\/a>vous aide \u00e0 visualiser cela avec une interface web facile pour le Raspberry Pi !)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quel syst\u00e8me d'exploitation dois-je utiliser sur mon Raspberry Pi ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons d\u00e9j\u00e0 \u00e9tabli que le syst\u00e8me d'exploitation de votre Raspberry Pi est la base de toutes les autres applications qui fonctionneront dessus. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le choix du bon syst\u00e8me d'exploitation pour votre Raspberry Pi est donc important. Il d\u00e9pend de ce que vous voulez faire avec votre Raspberry Pi. Dans cet article, je vous donne un aper\u00e7u des syst\u00e8mes d'exploitation les plus courants sur le Raspberry Pi. Cela vous inspirera peut-\u00eatre m\u00eame des id\u00e9es de projets, afin que vous puissiez apprendre de nouvelles choses que vous pouvez faire avec un Raspberry Pi \ud83d\ude42 .<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heureusement, il est tr\u00e8s facile d'exp\u00e9rimenter : il suffit d'une carte microSD suppl\u00e9mentaire pour changer de syst\u00e8me d'exploitation - vous pouvez m\u00eame installer plusieurs syst\u00e8mes d'exploitation sur une carte SD et choisir celui que vous voulez au moment du d\u00e9marrage, avec NOOBS. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"noobs\">NOOBS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">NOOBS signifie \"New out of Box Software\". Il ne s'agit pas d'un syst\u00e8me d'exploitation \u00e0 proprement parler, mais d'un environnement multi-boot pour plusieurs syst\u00e8mes d'exploitation. NOOBS est un bon choix pour les d\u00e9butants, car il vous permettra de r\u00e9installer facilement le syst\u00e8me d'exploitation si vous cassez quelque chose par accident. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re fois que vous d\u00e9marrez NOOBS, vous obtenez un \u00e9cran d'installation qui vous permet de choisir le syst\u00e8me d'exploitation que vous souhaitez utiliser sur votre Raspberry Pi. Pour revenir \u00e0 NOOBS, red\u00e9marrez votre Raspberry Pi et appuyez sur la touche Majuscule (et maintenez-la enfonc\u00e9e). Cela vous permettra de r\u00e9installer le syst\u00e8me d'exploitation.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez <a href=\"https:\/\/www.raspberrypi.org\/downloads\/noobs\/\">pour les NOOBs ici<\/a> \u00e0 partir de la page de t\u00e9l\u00e9chargement du Raspberry Pi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par d\u00e9faut, NOOBS contient <strong><a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> <\/strong>et <strong><a href=\"#libreelec\">LibreELEC<\/a><\/strong>. Il prend \u00e9galement en charge d'autres syst\u00e8mes d'exploitation, qu'il t\u00e9l\u00e9chargera et installera pour vous (si vous disposez d'une connexion Internet). <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quels sont les autres syst\u00e8mes d'exploitation pris en charge par NOOBS ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voici la liste compl\u00e8te des syst\u00e8mes d'exploitation actuellement pris en charge par NOOBS :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a><\/li>\n\n\n\n<li><a href=\"#libreelec\">LibreELEC<\/a><\/li>\n\n\n\n<li><a href=\"#osmc\">OSMC<\/a><\/li>\n\n\n\n<li><a href=\"#recalbox\">Recalbox<\/a><\/li>\n\n\n\n<li><a href=\"#lakka\">Lakka<\/a><\/li>\n\n\n\n<li><a href=\"#riscos\">RISC OS<\/a><\/li>\n\n\n\n<li><a href=\"#screenlyose\">Screenly OSE<\/a><\/li>\n\n\n\n<li><a href=\"#windows10coreiot\">Windows 10 IoT Core<\/a><\/li>\n\n\n\n<li><a href=\"#tlxos\">TLXOS<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Comment configurer un syst\u00e8me d'exploitation sur mon Raspberry Pi ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous sugg\u00e9rons d'utiliser l'imageur Raspberry Pi. <a href=\"https:\/\/picockpit.com\/raspberry-pi\/what-is-a-raspberry-pi-and-what-can-i-do-with-it\/\">Pour en savoir plus, consultez notre article sur le Raspberry Pi.<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-28.png\" alt=\"Capture d&#039;\u00e9cran de Raspberry Pi Imager montrant les diff\u00e9rentes versions d&#039;Ubuntu pour le Raspberry Pi et leur compatibilit\u00e9 (RPi 4\/400, RPi 2\/3\/4\/400, RPi 3\/4\/400) \" class=\"wp-image-163\" style=\"width:559px;height:376px\" width=\"559\" height=\"376\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-28.png 699w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-28-300x202.png 300w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><figcaption class=\"wp-element-caption\">Raspberry Pi Imager vous indique les versions de Raspberry Pi pour lesquelles le syst\u00e8me d'exploitation fonctionnera.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Lisez la suite pour en savoir plus sur les diff\u00e9rents syst\u00e8mes d'exploitation disponibles pour votre Raspberry Pi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Raspberry Pi OS (pr\u00e9c\u00e9demment appel\u00e9 Raspbian) est le syst\u00e8me d'exploitation standard du Raspberry Pi. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Notez qu'il peut y avoir une certaine confusion lorsque l'on parle de syst\u00e8mes d'exploitation en g\u00e9n\u00e9ral, car ceux-ci sont \u00e9galement abr\u00e9g\u00e9s en OS - en g\u00e9n\u00e9ral, Raspberry Pi OS signifie le syst\u00e8me d'exploitation fourni par le Raspberry Pi.<\/p>\n<cite>Raspi Berry clarifie les malentendus<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> Je recommande l'utilisation de Raspberry Pi OS en combinaison avec <a href=\"#noobs\">NOOBS<\/a> pour les personnes qui d\u00e9butent avec le Raspberry Pi.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot-1024x575.jpg\" alt=\"Capture d&#039;\u00e9cran du bureau de Raspberry Pi OS (anciennement appel\u00e9 Raspbian)\" class=\"wp-image-111\" style=\"width:645px;height:362px\" width=\"645\" height=\"362\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot-1024x575.jpg 1024w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot-300x169.jpg 300w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot-768x432.jpg 768w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot-1536x863.jpg 1536w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg 1785w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><figcaption class=\"wp-element-caption\">Capture d'\u00e9cran du Raspberry Pi OS Desktop<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Ce syst\u00e8me d'exploitation moderne est bas\u00e9 sur Debian et prend en charge la plupart des fonctions et applications que vous attendez d'un ordinateur :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>surfer sur le web avec Chromium<\/li>\n\n\n\n<li>\u00e9couter des fichiers audio et regarder des films avec VLC<\/li>\n\n\n\n<li>cr\u00e9er des documents et utiliser des feuilles de calcul, en utilisant LibreOffice Writer et LibreOffice Calc<\/li>\n\n\n\n<li>d\u00e9velopper du code Python en utilisant <a href=\"https:\/\/thonny.org\/\">Thonny <\/a>ou utiliser le <a href=\"https:\/\/www.geany.org\/\">Geany IDE <\/a>pour un large \u00e9ventail de langages de programmation<\/li>\n\n\n\n<li>apprendre \u00e0 coder en utilisant <a href=\"https:\/\/scratch.mit.edu\/\">Grattez<\/a><\/li>\n\n\n\n<li>envoyer des courriers \u00e9lectroniques \u00e0 l'aide du client de messagerie Thunderbird<\/li>\n\n\n\n<li>jouer \u00e0 des jeux r\u00e9tro (si vous le souhaitez) <a href=\"https:\/\/retropie.org.uk\/docs\/Manual-Installation\/\">installer manuellement retropie<\/a>)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">et bien d'autres encore.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Raspberry Pi OS est \u00e9galement un excellent moyen de commencer \u00e0 utiliser les broches GPIO du Raspberry Pi, en ex\u00e9cutant un serveur de tout type (serveur d'impression \/ serveur web \/ serveur de fichiers \/ serveur SAMBA). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez \u00e9galement utiliser le tr\u00e8s populaire <a href=\"https:\/\/pi-hole.net\/\">Pi Hole<\/a> un bloqueur de publicit\u00e9s sur l'ensemble du r\u00e9seau sur le Raspberry Pi OS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour beaucoup de ces applications, il existe des OS Raspberry Pi distincts et sp\u00e9cialis\u00e9s. C'est un peu comme avec les outils : des outils tout-en-un peuvent \u00eatre utilis\u00e9s, et vous pouvez utiliser cet outil pour de nombreux usages. Mais si vous avez vraiment besoin d'un travail bien fait, vous devriez opter pour un syst\u00e8me d'exploitation sp\u00e9cialis\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ne manquez pas de terminer la lecture de cet article pour avoir une bonne vue d'ensemble !<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Raspberry Pi OS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez t\u00e9l\u00e9charger Raspberry Pi OS \u00e0 partir de la page <a href=\"https:\/\/www.raspberrypi.org\/downloads\/raspberry-pi-os\/\">Site officiel du Raspberry Pi<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les versions 32 bits (les versions par d\u00e9faut) fonctionneront correctement avec n'importe quel mod\u00e8le de Raspberry Pi.  La version 64 bits de Raspberry Pi OS n'est requise que pour des cas d'utilisation particuliers (et n'est peut-\u00eatre vraiment utile que pour le Raspberry Pi 4, qui dispose de plus de 1 Go de RAM). La version 64 bits ne fonctionnera pas avec les mod\u00e8les de Raspberry Pi ant\u00e9rieurs (Pi Zero W \/ Raspi Model 1 B \/ Raspberry Pi 2), car ceux-ci ont une architecture de jeu d'instructions (aka ISA) diff\u00e9rente (ARMv6 \/ ARMv7). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> En cas de doute, optez pour les versions 32 bits.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Quel syst\u00e8me d'exploitation Raspberry Pi dois-je choisir ?<\/h4>\n\n\n\n<h5 class=\"wp-block-heading\">Raspberry Pi OS (32 bits) avec bureau et logiciels recommand\u00e9s<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Cette version est la plus volumineuse et la plus longue \u00e0 t\u00e9l\u00e9charger. Elle comprend cependant un grand nombre de logiciels pr\u00eats \u00e0 l'emploi. Si vous disposez d'une carte SD de grande capacit\u00e9 (16 Go ou plus) et d'une connexion Internet rapide, optez pour cette version.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><br>Raspberry Pi OS (32-bit) avec bureau<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez utiliser un environnement de bureau confortable (comme celui auquel vous \u00eates peut-\u00eatre habitu\u00e9 avec Windows ou MacOS), mais que vous n'avez pas besoin de logiciels suppl\u00e9mentaires, optez pour celui-ci. <\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><br>Raspberry Pi OS (32-bit) Lite<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La version lite n'inclut pas le bureau. Si vous savez vous servir d'un terminal et que SSH n'est pas un charabia pour vous, et si vous cherchez la plus petite version possible du Raspberry Pi OS, t\u00e9l\u00e9chargez celle-ci. Id\u00e9al pour faire tourner des serveurs headless.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Comme indiqu\u00e9 pr\u00e9c\u00e9demment, nous recommandons aux d\u00e9butants de commencer par NOOBS (qui contient Raspberry Pi OS aka Raspbian). <a href=\"https:\/\/www.raspberrypi.org\/downloads\/noobs\/\">T\u00e9l\u00e9charger NOOBS ici<\/a>.<\/p>\n<cite>Les conseils de Raspi Berry sur le Raspberry Pi<\/cite><\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\">PiCockpit pour Raspberry Pi OS : votre interface web pratique pour l'acc\u00e8s \u00e0 distance de votre Pi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/picockpit.com\">PiCockpit<\/a> ne prend actuellement en charge que le Raspberry Pi OS (et ses d\u00e9riv\u00e9s, comme DietPi). Avec PiCockpit, vous pourrez g\u00e9rer, contr\u00f4ler et surveiller votre Raspberry Pi depuis n'importe o\u00f9 \u00e0 l'aide d'une interface web :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/picockpit.com\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/picockpit-system-camerasupport.jpg\" alt=\"Capture d&#039;\u00e9cran de PiCockpit PiDoctor montrant le mod\u00e8le de Raspberry Pi et quelques statistiques\" class=\"wp-image-112\" style=\"width:443px;height:579px\" width=\"443\" height=\"579\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/picockpit-system-camerasupport.jpg 714w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/picockpit-system-camerasupport-230x300.jpg 230w\" sizes=\"auto, (max-width: 443px) 100vw, 443px\" \/><\/a><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/picockpit.com\">PiCockpit <\/a>PiDoctor vous permet de surveiller votre Pi et d'obtenir des informations de mani\u00e8re agr\u00e9able et lisible.<\/figcaption><\/figure>\n<\/div>\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/picockpit.com\">En savoir plus sur PiCockpit<\/a><\/div>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous souhaitez utiliser PiCockpit et les fonctionnalit\u00e9s qu'il offre, je vous recommande donc d'opter pour Raspberry Pi OS.<\/p>\n<cite>Conseils utiles de Raspi Berry sur le Raspberry Pi et le PiCockpit<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"libreelec\">LibreELEC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">LibreELEC est un syst\u00e8me d'exploitation sp\u00e9cialis\u00e9 dans la visualisation de m\u00e9dias sur les t\u00e9l\u00e9viseurs. Pour cet usage particulier, c'est l'un des syst\u00e8mes d'exploitation les plus populaires sur le Raspberry Pi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LibreELEC se compose d'une pl\u00e9thore de plugins, vous permettant de.. :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>diffuser des vid\u00e9os (par exemple sur YouTube)<\/li>\n\n\n\n<li>\u00e9couter de la musique (diffuser de la musique en continu, \u00e0 partir de cha\u00eenes de radio en ligne, ou lire des fichiers que vous avez enregistr\u00e9s sur votre disque dur ou sur un serveur de votre r\u00e9seau)<\/li>\n\n\n\n<li>v\u00e9rifier la m\u00e9t\u00e9o<\/li>\n\n\n\n<li>jouer \u00e0 des jeux r\u00e9tro <\/li>\n\n\n\n<li>t\u00e9l\u00e9commande de lecture LibreELEC, \u00e0 partir de votre smartphone<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ces plugins peuvent \u00eatre install\u00e9s facilement \u00e0 partir de l'interface de LibreELEC. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\"Juste assez d'OS pour KODI\" : LibreELEC est bas\u00e9 sur le projet KODI, qui est un effort communautaire pour d\u00e9velopper une application de centre multim\u00e9dia. KODI a besoin d'un syst\u00e8me d'exploitation pour fonctionner. LibreELEC compile le code de KODI et ajoute juste assez de code Linux suppl\u00e9mentaire pour que KODI fonctionne.<\/p>\n<cite>Le Raspberry Pi expliqu\u00e9 par Raspi Berry<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">LibreELEC est tr\u00e8s appropri\u00e9 si vous voulez un centre de divertissement \u00e0 domicile, bas\u00e9 sur le Raspberry Pi. Nous vous recommandons d'utiliser le logiciel <a href=\"https:\/\/buyzero.de\/products\/raspberry-pi-4-model-b?variant=28034031812710\">Raspberry Pi 4<\/a>. Ne manquez pas de jeter un coup d'\u0153il sur le site <a href=\"https:\/\/buyzero.de\/products\/flirc-gehause-fur-raspberry-pi-4?variant=31142645891174\">Le cas FLIRC<\/a> car le Pi 4 fonctionnera mieux avec.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous souhaitez surfer sur le web, r\u00e9diger des documents et apprendre \u00e0 coder, vous devriez cependant opter pour Raspberry Pi OS.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger LibreELEC<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez <a href=\"https:\/\/libreelec.tv\/downloads_new\/\">t\u00e9l\u00e9charger LibreELEC ici<\/a>. Faites d\u00e9filer jusqu'\u00e0 \"Direct downloads\" et cliquez sur Raspberry Pi :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-24-1024x361.png\" alt=\"\" class=\"wp-image-124\" style=\"width:732px;height:258px\" width=\"732\" height=\"258\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-24-1024x361.png 1024w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-24-300x106.png 300w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-24-768x271.png 768w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-24.png 1514w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><figcaption class=\"wp-element-caption\">Capture d'\u00e9cran de la zone de t\u00e9l\u00e9chargement de LibreELEC<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cela filtrera la liste et ne vous montrera que les t\u00e9l\u00e9chargements pour Raspberry Pi. Choisissez maintenant le mod\u00e8le de Raspberry Pi que vous avez, car LibreELEC a des versions optimis\u00e9es pour diff\u00e9rents Raspberry Pis. (Le Raspberry Pi 4, par exemple, supporte le d\u00e9codage H.265 \/ HEVC en mat\u00e9riel, alors que d'autres ne le supportent pas). <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le meilleur Raspberry Pi pour LibreELEC<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En tant que centre de m\u00e9dias, le <a href=\"https:\/\/buyzero.de\/products\/raspberry-pi-4-model-b?variant=28034031812710\">Raspberry Pi 4<\/a> est le meilleur choix, en raison de sa puissance de traitement et de la prise en charge mat\u00e9rielle de H.265 \/ HEVC. Nous recommandons le <a href=\"https:\/\/buyzero.de\/products\/flirc-gehause-fur-raspberry-pi-4?variant=31142645891174\">Le cas FLIRC<\/a> pour l'accompagner et am\u00e9liorer ses performances.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"osmc\">OSMC<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'OSMC, comme <a href=\"#libreelec\">LibreELEC<\/a>Ce logiciel vous permet d'ex\u00e9cuter votre propre centre multim\u00e9dia sur le Raspberry Pi. Pour l'instant, il ne prend pas en charge le Raspberry Pi 4, qui serait le choix optimal pour un centre multim\u00e9dia. C'est pourquoi je vous recommande de consulter <a href=\"#libreelec\">LibreELEC<\/a> si c'est ce que vous voulez faire avec un Raspberry Pi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">OSMC est le successeur de Raspbmc. Comme <a href=\"#libreelec\">LibreELEC <\/a>il est \u00e9galement bas\u00e9 sur KODI.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger l'OSMC<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> OSMC pour Raspberry Pi 2 \/ 3 \/ 3+ et Pi 1 \/ Zero \/ Zero W <a href=\"https:\/\/osmc.tv\/download\/\">peut \u00eatre t\u00e9l\u00e9charg\u00e9e ici.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"recalbox\">Recalbox<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.recalbox.com\/\">Recalbox <\/a>est une application open source de console de retrogaming. Vous pouvez jouer \u00e0 de vieux jeux (si vous avez les ROMs), tels que NES, MEGADRIVE, Playstation, et Nintendo64 sur votre Raspberry Pi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les besoins du r\u00e9trogaming, le <a href=\"https:\/\/buyzero.de\/products\/raspberry-pi-4-model-b?variant=28034031812710\">Raspberry Pi 4<\/a> est le meilleur choix, en raison de sa puissance de traitement. Nous recommandons le <a href=\"https:\/\/buyzero.de\/products\/flirc-gehause-fur-raspberry-pi-4?variant=31142645891174\">Le cas FLIRC<\/a> pour l'accompagner et am\u00e9liorer ses performances.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Recalbox<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/download.recalbox.com\/\">T\u00e9l\u00e9chargez Recalbox ici<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"lakka\">Lakka<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lakka est une autre solution de Retrogaming, bas\u00e9e sur l'\u00e9mulateur RetroArch. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Lakka<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.lakka.tv\/get\/linux\/\">T\u00e9l\u00e9charger Lakka ici<\/a>. Pour voir la version Raspberry Pi 4, vous devez faire d\u00e9filer la page vers le bas. Je vous souhaite la bienvenue \ud83d\ude42 .<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"riscos\">RISC OS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il s'agit probablement du plus ancien syst\u00e8me d'exploitation pr\u00e9sent\u00e9 ici. Avec le syst\u00e8me d'exploitation <a href=\"#windows10coreiot\">Windows 10 Core IoT<\/a> c'est aussi le seul qui ne soit pas bas\u00e9 sur Linux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">RISC a une longue histoire qui est \u00e9galement li\u00e9e au Raspberry Pi. RISC OS a \u00e9galement \u00e9t\u00e9 le tout premier syst\u00e8me d'exploitation \u00e0 fonctionner sur les puces ARM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il pr\u00e9sente surtout un int\u00e9r\u00eat historique, mais il est toujours en cours de d\u00e9veloppement par le RISC OS Open Group.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger RISC OS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.riscosopen.org\/content\/downloads\/raspberry-pi\">T\u00e9l\u00e9chargez RISC OS ici<\/a>. Il prend en charge tous les mod\u00e8les de Raspberry Pi actuellement sur le march\u00e9 (le Compute Module 4 n'est pas mentionn\u00e9 explicitement, mais il prend en charge le Pi 4 Model B). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"screenlyose\">Screenly OSE<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Screenly OSE (Open Source Edition) est un logiciel d'affichage dynamique gratuit. Il permet d'afficher des images Full HD 1080p, des vid\u00e9os et des pages web en direct. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Screenly dispose \u00e9galement d'une \u00e9dition payante, qui vous permettra de g\u00e9rer les Raspberry Pis.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Screenly OSE<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/github.com\/screenly\/screenly-ose\/releases\">T\u00e9l\u00e9chargez-le depuis GitHub ici<\/a>. Ou l'installer en utilisant <a href=\"#noobs\">NOOBS<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tlxos\">TLXOS<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous savez ce qu'est un client l\u00e9ger, un affichage dynamique ou une passerelle IoT et que vous souhaitez en construire un \u00e0 partir d'un Raspberry Pi, ce syst\u00e8me est fait pour vous. Notez que vous b\u00e9n\u00e9ficierez d'un essai gratuit de 30 jours - une licence TLXOS co\u00fbte de $5 \u00e0 $10, en fonction de votre mod\u00e8le de Raspberry Pi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Clients l\u00e9gers<\/strong> vous permettent d'acc\u00e9der \u00e0 des serveurs distants, qui effectuent le traitement, d'afficher leurs r\u00e9sultats et de prendre des donn\u00e9es locales et de les envoyer au serveur. TLXOS est compatible avec Citrix HDX, VMware Horizon et Microsoft RDP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notez que vous pourrez \u00e9galement obtenir un certain succ\u00e8s en utilisant <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> et des logiciels libres (gratuits) pour cr\u00e9er un client l\u00e9ger. Pour les installations de masse, TLXOS pourrait \u00eatre plus pratique et plus riche en fonctionnalit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signalisation num\u00e9rique<\/strong> permet d'afficher des diaporamas, des vid\u00e9os, des images statiques ou d'autres informations. Le Raspberry Pi est utilis\u00e9 comme p\u00e9riph\u00e9rique de sortie uniquement. L\u00e0 encore, cette fonctionnalit\u00e9 peut \u00eatre obtenue gratuitement en modifiant le fichier <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a>mais si vous voulez une solution rapide et facile (et aussi une solution \u00e9volutive), TLXOS peut \u00eatre un bon choix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Passerelles IoT<\/strong> connectent g\u00e9n\u00e9ralement des capteurs et des appareils Bluetooth \u00e0 l'internet (IoT est l'abr\u00e9viation d'Internet of things). Le Raspberry Pi sert de n\u0153ud interm\u00e9diaire pour permettre \u00e0 ces appareils de transmettre leurs donn\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TLXOS est d\u00e9velopp\u00e9 par <a href=\"https:\/\/thinlinx.com\/\">ThinLinX Pty Ltd<\/a>une soci\u00e9t\u00e9 australienne. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger TLXOS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez <a href=\"https:\/\/thinlinx.com\/download\/\">T\u00e9l\u00e9charger TLXOS ici<\/a>. Il est \u00e9galement inclus dans le programme d'installation de NOOBS. Note : au d\u00e9part, vous b\u00e9n\u00e9ficierez d'une p\u00e9riode d'essai gratuite de 30 jours, mais vous devrez <a href=\"https:\/\/thinlinx.com\/buy\/\">acheter une licence<\/a> de continuer \u00e0 utiliser le syst\u00e8me.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"alpine\">Linux alpin<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alpine Linux est une distribution Linux simple, ax\u00e9e sur une taille r\u00e9duite et une bonne s\u00e9curit\u00e9. Vous n'obtiendrez que les \u00e9l\u00e9ments essentiels dont vous avez besoin, et installerez tous les autres paquets relatifs \u00e0 votre projet. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alpine Linux est fr\u00e9quemment utilis\u00e9 comme syst\u00e8me d'exploitation de base pour les images de conteneurs Docker. Un point technique important \u00e0 noter est qu'Alpine utilise busybox et musl comme libc (et non glibc).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nous utilisons Alpine Linux pour le d\u00e9veloppement embarqu\u00e9.<\/strong> Contactez-nous si vous avez besoin de services de conseil ou de d\u00e9veloppement pour la plateforme Raspberry Pi. Nous proposons \u00e0 la fois le d\u00e9veloppement de logiciels et de mat\u00e9riel, et nous pouvons aider votre cha\u00eene d'approvisionnement en vous procurant le mat\u00e9riel Raspberry Pi. <\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\">contacter pi3g e.K. <br>(D\u00e9veloppement de logiciels et de mat\u00e9riel embarqu\u00e9s Raspberry Pi)<\/a><\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Alpine Linux<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous pouvez <a href=\"https:\/\/www.alpinelinux.org\/downloads\/\">t\u00e9l\u00e9charger Alpine Linux pour Raspberry Pi ici<\/a>. Assurez-vous de s\u00e9lectionner la bonne architecture (aarch64 \/ armhf \/ armv7).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"suse\">SuSE Linux<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">SuSE est une soci\u00e9t\u00e9 allemande qui propose une version gratuite (OpenSUSE) et une version commerciale de Linux (SLES - SuSE Linux Enterprise Server) pour le Raspberry Pi.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger SuSE Linux<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">OpenSuSE supporte aarch64 (Raspberry Pi 4), mais pas les autres architectures Raspberry Pi. <a href=\"https:\/\/software.opensuse.org\/distributions\/leap\">T\u00e9l\u00e9chargez-le ici<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.suse.com\/download\/sles\/\">SLES peut \u00eatre t\u00e9l\u00e9charg\u00e9 ici<\/a>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Si vous souhaitez disposer des paquets les plus r\u00e9cents et participer au d\u00e9veloppement de SuSE, jetez un coup d'\u0153il \u00e0 OpenSuSE. <a href=\"https:\/\/software.opensuse.org\/distributions\/tumbleweed\">Le bourdon<\/a>. Les autres utilisateurs devraient opter pour Leap.<\/p>\n<cite>Les conseils utiles de Raspi Berry sur SuSe<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"windows10coreiot\">Windows 10 Core IoT<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cette variante de Windows est fournie par Microsoft pour le Raspberry Pi. Cependant, elle <strong>pas <\/strong>vous permettent d'ex\u00e9cuter des applications de bureau \"classiques\", telles que Microsoft Word ou Excel, sur le Raspberry Pi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Windows 10 Core IoT est con\u00e7u pour les entreprises qui souhaitent ex\u00e9cuter du code sur le Raspberry Pi et construire leurs propres appareils IoT (\u00e9galement appel\u00e9 \"syst\u00e8me d'exploitation embarqu\u00e9\"). Notez que Windows 10 Core IoT est gratuit pour l'\u00e9valuation, mais que vous devez acheter une licence commerciale aupr\u00e8s de Microsoft pour l'utiliser \u00e0 des fins commerciales (comme, par exemple, des distributeurs automatiques).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates \u00e0 la recherche d'une entreprise capable de d\u00e9velopper pour vous des solutions logicielles et mat\u00e9rielles embarqu\u00e9es, n'h\u00e9sitez pas \u00e0 prendre contact avec nous :<\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-7d812b4c wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\">contacter pi3g e.K. <br>(D\u00e9veloppement de logiciels et de mat\u00e9riel embarqu\u00e9s Raspberry Pi)<\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Certains utilisateurs ont r\u00e9ussi \u00e0 faire fonctionner d'autres variantes (de bureau) de Windows sur le Raspberry Pi. Si les applications classiques d\u00e9marrent sur le Pi, elles seront toutefois tr\u00e8s lentes, car la plupart des applications Windows sont optimis\u00e9es pour une architecture de CPU diff\u00e9rente (x86) de celle du Raspberry Pi (ARM). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il faut donc les \u00e9muler - imaginez que quelqu'un parle espagnol et que, pour le comprendre, vous deviez demander \u00e0 une autre personne de traduire tout ce qu'il dit et tout ce que vous dites. La conversation serait beaucoup plus lente - et il en va de m\u00eame pour l'\u00e9mulation. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">T\u00e9l\u00e9charger Windows 10 Core IoT<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.microsoft.com\/en-us\/software-download\/windows10iotcore\">Windows 10 CoreIoT pour Raspberry Pi 2 \/ 3 peut \u00eatre t\u00e9l\u00e9charg\u00e9 ici.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Attention, il n'y a pas de version pour le Raspberry Pi 4 actuellement. La derni\u00e8re version pour le Raspberry Pi date d'octobre 2018.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R\u00e9cup\u00e9ration du d\u00e9marrage de l'EEPROM du Raspberry Pi 4<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Raspberry Pi Imager vous permet \u00e9galement de choisir \"Misc utility images\" (r\u00e9cup\u00e9ration EEPROM, etc.). Faites d\u00e9filer la liste des syst\u00e8mes d'exploitation vers le bas pour les voir :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-29.png\" alt=\"Capture d&#039;\u00e9cran de l&#039;imageur Raspberry Pi, montrant RISC OS Pi, TLXOS, Misc utility images, erase and use custom\" class=\"wp-image-165\" style=\"width:612px;height:410px\" width=\"612\" height=\"410\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-29.png 699w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-29-300x201.png 300w\" sizes=\"auto, (max-width: 612px) 100vw, 612px\" \/><figcaption class=\"wp-element-caption\">Imageur Raspberry Pi, montrant un choix de syst\u00e8mes d'exploitation.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Cliquez sur \"Misc utility images\" pour voir l'image de r\u00e9cup\u00e9ration du d\u00e9marrage de l'EEPROM du Raspberry Pi 4, avec le texte \"Use this only if advised to do so\" (N'utilisez cette image que si on vous le conseille) en dessous :<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-30.png\" alt=\"Raspberry Pi Imager montrant l&#039;\u00e9cran de r\u00e9cup\u00e9ration du d\u00e9marrage de l&#039;EEPROM du Raspberry Pi 4.\" class=\"wp-image-166\" style=\"width:602px;height:406px\" width=\"602\" height=\"406\" srcset=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-30.png 700w, https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/image-30-300x202.png 300w\" sizes=\"auto, (max-width: 602px) 100vw, 602px\" \/><figcaption class=\"wp-element-caption\">Image de r\u00e9cup\u00e9ration du d\u00e9marrage de l'EEPROM du Raspberry Pi 4<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Il ne s'agit pas d'un syst\u00e8me d'exploitation \u00e0 proprement parler, mais d'un utilitaire d'aide. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Raspberry Pi 4 poss\u00e8de un \u00e9tage de d\u00e9marrage suppl\u00e9mentaire (une EEPROM) qui lui permet d'ajouter des capacit\u00e9s de d\u00e9marrage suppl\u00e9mentaires sous la forme de mises \u00e0 jour logicielles. Il arrive que cette EEPROM pose des probl\u00e8mes et qu'elle doive \u00eatre r\u00e9\u00e9crite. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, si votre Raspberry Pi ne d\u00e9marre pas \u00e0 partir de cartes SD qui sont connues pour avoir un syst\u00e8me d'exploitation bon et compatible, vous pouvez essayer cette image de r\u00e9cup\u00e9ration de d\u00e9marrage de l'EEPROM du Raspberry Pi 4 pour tenter de reflasher l'EEPROM. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ceci ne sera d'aucune utilit\u00e9 pour les autres mod\u00e8les de Raspberry Pi (Pi Zero \/ Pi 1 \/ Pi 2 \/ Pi 3).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il existe de nombreuses variantes du syst\u00e8me d'exploitation du Raspberry Pi. Pour de nombreux utilisateurs <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> (qui peut \u00eatre install\u00e9 \u00e0 l'aide de <a href=\"#noobs\">NOOBS<\/a>par exemple) sera le choix id\u00e9al, car il vous permet de faire la plupart des choses assez bien. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> sur votre Raspberry Pi, <a href=\"https:\/\/picockpit.com\">ne manquez pas de jeter un coup d'\u0153il \u00e0 PiCockpit <\/a>- il vous aidera \u00e0 g\u00e9rer votre syst\u00e8me et \u00e0 utiliser le port GPIO, etc.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous aimez les syst\u00e8mes de divertissement \u00e0 domicile, vous devriez jeter un coup d'\u0153il \u00e0 <a href=\"#libreelec\">LibreELEC<\/a>au lieu de cela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Windows sur Raspberry Pi n'est pas encore une r\u00e9alit\u00e9, vous devriez vous pencher sur la solution Linux. <a href=\"#raspberrypios\">Syst\u00e8me d'exploitation Raspberry Pi<\/a> et des alternatives logicielles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quel syst\u00e8me d'exploitation pr\u00e9f\u00e9rez-vous utiliser sur le Raspberry Pi ? Quelles sont vos exp\u00e9riences et vos recommandations ? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Commentez ci-dessous pour nous faire part de votre sagesse \ud83d\ude42 .<\/strong><\/p>\n<div class=\"shariff shariff-align-center shariff-widget-align-left shariff-buttonstretch\"><ul class=\"shariff-buttons theme-white orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fpicockpit.com%2Fraspberry-pi%2Ffr%2Fapercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi%2F&text=Raspberry%20Pi%20OS%20Overview\" title=\"Envoyer par X\" aria-label=\"Envoyer par X\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#000\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#000\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#000\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fpicockpit.com%2Fraspberry-pi%2Ffr%2Fapercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi%2F\" title=\"Envoyer par Facebook\" aria-label=\"Envoyer par Facebook\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#3b5998\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#3b5998\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#3b5998\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button telegram shariff-nocustomcolor\" style=\"background-color:#4084A6\"><a href=\"https:\/\/telegram.me\/share\/url?url=https%3A%2F%2Fpicockpit.com%2Fraspberry-pi%2Ffr%2Fapercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi%2F&text=Raspberry%20Pi%20OS%20Overview\" title=\"Envoyer par Telegram\" aria-label=\"Envoyer par Telegram\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0088cc; color:#0088cc\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#0088cc\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 32 32\"><path fill=\"#0088cc\" d=\"M30.8 6.5l-4.5 21.4c-.3 1.5-1.2 1.9-2.5 1.2L16.9 24l-3.3 3.2c-.4.4-.7.7-1.4.7l.5-7L25.5 9.2c.6-.5-.1-.8-.9-.3l-15.8 10L2 16.7c-1.5-.5-1.5-1.5.3-2.2L28.9 4.3c1.3-.5 2.3.3 1.9 2.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#0088cc\">partager<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button reddit shariff-nocustomcolor\" style=\"background-color:#ff5700\"><a href=\"https:\/\/www.reddit.com\/submit?url=https%3A%2F%2Fpicockpit.com%2Fraspberry-pi%2Ffr%2Fapercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi%2F\" title=\"Envoyer par Reddit\" aria-label=\"Envoyer par Reddit\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#ff4500; color:#ff4500\" target=\"_blank\"><span class=\"shariff-icon\" style=\"fill:#ff4500\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\"><path fill=\"#ff4500\" d=\"M440.3 203.5c-15 0-28.2 6.2-37.9 15.9-35.7-24.7-83.8-40.6-137.1-42.3L293 52.3l88.2 19.8c0 21.6 17.6 39.2 39.2 39.2 22 0 39.7-18.1 39.7-39.7s-17.6-39.7-39.7-39.7c-15.4 0-28.7 9.3-35.3 22l-97.4-21.6c-4.9-1.3-9.7 2.2-11 7.1L246.3 177c-52.9 2.2-100.5 18.1-136.3 42.8-9.7-10.1-23.4-16.3-38.4-16.3-55.6 0-73.8 74.6-22.9 100.1-1.8 7.9-2.6 16.3-2.6 24.7 0 83.8 94.4 151.7 210.3 151.7 116.4 0 210.8-67.9 210.8-151.7 0-8.4-.9-17.2-3.1-25.1 49.9-25.6 31.5-99.7-23.8-99.7zM129.4 308.9c0-22 17.6-39.7 39.7-39.7 21.6 0 39.2 17.6 39.2 39.7 0 21.6-17.6 39.2-39.2 39.2-22 .1-39.7-17.6-39.7-39.2zm214.3 93.5c-36.4 36.4-139.1 36.4-175.5 0-4-3.5-4-9.7 0-13.7 3.5-3.5 9.7-3.5 13.2 0 27.8 28.5 120 29 149 0 3.5-3.5 9.7-3.5 13.2 0 4.1 4 4.1 10.2.1 13.7zm-.8-54.2c-21.6 0-39.2-17.6-39.2-39.2 0-22 17.6-39.7 39.2-39.7 22 0 39.7 17.6 39.7 39.7-.1 21.5-17.7 39.2-39.7 39.2z\"\/><\/svg><\/span><span class=\"shariff-text\" style=\"color:#ff4500\">partager<\/span>&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Syst\u00e8mes d'exploitation pour chaque cas d'utilisation du Raspi Un syst\u00e8me d'exploitation Raspberry Pi pour tous : le Pi prend en charge de nombreux syst\u00e8mes d'exploitation diff\u00e9rents. Dans cet article, vous aurez une vue d'ensemble des syst\u00e8mes d'exploitation populaires pour le Raspi, et vous saurez quel syst\u00e8me d'exploitation vous devriez choisir pour votre projet \/ cas d'utilisation. Pour les d\u00e9butants et la plupart des cas d'utilisation, le syst\u00e8me d'exploitation Raspberry Pi...<\/p>","protected":false},"author":2,"featured_media":111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1121,602,1126,776,1117,1113,1114,1123,1116,1124,1125,187,636,783,538,600,803,1118,1119,1122,1120,1115,685],"class_list":["post-110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-raspberry-pi-how-to","tag-alpine-linux","tag-desktop","tag-eeprom-boot-recovery","tag-id-eeprom","tag-lakka","tag-libreelec","tag-noobs","tag-operating-system","tag-osmc","tag-pi-hole","tag-pihole","tag-raspberry-pi","tag-raspberry-pi-4","tag-raspberry-pi-os","tag-raspberry-pi-zero","tag-raspbian","tag-recalbox","tag-risc-os","tag-screenly-ose","tag-suse-linux","tag-tlxos","tag-windows-10-core-iot","tag-zero"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raspberry Pi OS Overview | PiCockpit<\/title>\n<meta name=\"description\" content=\"Tutorials\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/picockpit.com\/raspberry-pi\/fr\/apercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raspberry Pi OS Overview | PiCockpit\" \/>\n<meta property=\"og:description\" content=\"Tutorials\" \/>\n<meta property=\"og:url\" content=\"https:\/\/picockpit.com\/raspberry-pi\/fr\/apercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi\/\" \/>\n<meta property=\"og:site_name\" content=\"PiCockpit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pi3gshop\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-10T10:43:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T11:04:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1785\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"raspi berry\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@pi3g\" \/>\n<meta name=\"twitter:site\" content=\"@pi3g\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"raspi berry\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/\"},\"author\":{\"name\":\"raspi berry\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#\\\/schema\\\/person\\\/7af3a7a8c999bc722029ef9ca9d78eee\"},\"headline\":\"Raspberry Pi OS Overview\",\"datePublished\":\"2020-11-10T10:43:53+00:00\",\"dateModified\":\"2023-08-30T11:04:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/\"},\"wordCount\":3148,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/raspberry-pi-os-screenshot.jpg\",\"keywords\":[\"Alpine Linux\",\"desktop\",\"EEPROM boot recovery\",\"ID EEPROM\",\"Lakka\",\"LibreELEC\",\"NOOBS\",\"operating system\",\"OSMC\",\"pi hole\",\"pihole\",\"Raspberry Pi\",\"Raspberry Pi 4\",\"Raspberry Pi OS\",\"Raspberry Pi Zero\",\"Raspbian\",\"recalbox\",\"RISC OS\",\"Screenly OSE\",\"SuSE Linux\",\"TLXOS\",\"Windows 10 Core IoT\",\"Zero\"],\"articleSection\":[\"Tutorials\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/\",\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/\",\"name\":\"Raspberry Pi OS Overview | PiCockpit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/raspberry-pi-os-screenshot.jpg\",\"datePublished\":\"2020-11-10T10:43:53+00:00\",\"dateModified\":\"2023-08-30T11:04:30+00:00\",\"description\":\"Tutorials\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#primaryimage\",\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/raspberry-pi-os-screenshot.jpg\",\"contentUrl\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/raspberry-pi-os-screenshot.jpg\",\"width\":1785,\"height\":1003},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/raspberry-pi-os-overview\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutorials\",\"item\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/category\\\/raspberry-pi-how-to\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Raspberry Pi OS Overview\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#website\",\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/\",\"name\":\"PiCockpit\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#organization\",\"name\":\"PiCockpit.com\",\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Screenshot-from-2023-07-24-15-01-24.png\",\"contentUrl\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Screenshot-from-2023-07-24-15-01-24.png\",\"width\":1165,\"height\":283,\"caption\":\"PiCockpit.com\"},\"image\":{\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pi3gshop\",\"https:\\\/\\\/x.com\\\/pi3g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/#\\\/schema\\\/person\\\/7af3a7a8c999bc722029ef9ca9d78eee\",\"name\":\"raspi berry\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g\",\"caption\":\"raspi berry\"},\"description\":\"I'm here to help you with all your Raspberry Pi related questions &amp; love to share about new project ideas for the Raspberry Pi, and give quick tips. Of course I'll also help you with PiCockpit and how to make your Raspberry Pi even easier to use with this raspberry pi monitoring solution :-)\",\"sameAs\":[\"https:\\\/\\\/picockpit.com\"],\"url\":\"https:\\\/\\\/picockpit.com\\\/raspberry-pi\\\/fr\\\/author\\\/raspi-berry\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aper\u00e7u du syst\u00e8me d'exploitation du Raspberry Pi | PiCockpit","description":"Tutoriels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/picockpit.com\/raspberry-pi\/fr\/apercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi\/","og_locale":"fr_FR","og_type":"article","og_title":"Raspberry Pi OS Overview | PiCockpit","og_description":"Tutorials","og_url":"https:\/\/picockpit.com\/raspberry-pi\/fr\/apercu-du-systeme-dexploitation-de-la-framboise-raspberry-pi\/","og_site_name":"PiCockpit","article_publisher":"https:\/\/www.facebook.com\/pi3gshop","article_published_time":"2020-11-10T10:43:53+00:00","article_modified_time":"2023-08-30T11:04:30+00:00","og_image":[{"width":1785,"height":1003,"url":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg","type":"image\/jpeg"}],"author":"raspi berry","twitter_card":"summary_large_image","twitter_creator":"@pi3g","twitter_site":"@pi3g","twitter_misc":{"\u00c9crit par":"raspi berry","Dur\u00e9e de lecture estim\u00e9e":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#article","isPartOf":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/"},"author":{"name":"raspi berry","@id":"https:\/\/picockpit.com\/raspberry-pi\/#\/schema\/person\/7af3a7a8c999bc722029ef9ca9d78eee"},"headline":"Raspberry Pi OS Overview","datePublished":"2020-11-10T10:43:53+00:00","dateModified":"2023-08-30T11:04:30+00:00","mainEntityOfPage":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/"},"wordCount":3148,"commentCount":1,"publisher":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/#organization"},"image":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#primaryimage"},"thumbnailUrl":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg","keywords":["Alpine Linux","desktop","EEPROM boot recovery","ID EEPROM","Lakka","LibreELEC","NOOBS","operating system","OSMC","pi hole","pihole","Raspberry Pi","Raspberry Pi 4","Raspberry Pi OS","Raspberry Pi Zero","Raspbian","recalbox","RISC OS","Screenly OSE","SuSE Linux","TLXOS","Windows 10 Core IoT","Zero"],"articleSection":["Tutorials"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/","url":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/","name":"Aper\u00e7u du syst\u00e8me d'exploitation du Raspberry Pi | PiCockpit","isPartOf":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#primaryimage"},"image":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#primaryimage"},"thumbnailUrl":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg","datePublished":"2020-11-10T10:43:53+00:00","dateModified":"2023-08-30T11:04:30+00:00","description":"Tutoriels","breadcrumb":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#primaryimage","url":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg","contentUrl":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2020\/11\/raspberry-pi-os-screenshot.jpg","width":1785,"height":1003},{"@type":"BreadcrumbList","@id":"https:\/\/picockpit.com\/raspberry-pi\/raspberry-pi-os-overview\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/picockpit.com\/raspberry-pi\/"},{"@type":"ListItem","position":2,"name":"Tutorials","item":"https:\/\/picockpit.com\/raspberry-pi\/category\/raspberry-pi-how-to\/"},{"@type":"ListItem","position":3,"name":"Raspberry Pi OS Overview"}]},{"@type":"WebSite","@id":"https:\/\/picockpit.com\/raspberry-pi\/#website","url":"https:\/\/picockpit.com\/raspberry-pi\/","name":"PiCockpit","description":"","publisher":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/picockpit.com\/raspberry-pi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/picockpit.com\/raspberry-pi\/#organization","name":"PiCockpit.com","url":"https:\/\/picockpit.com\/raspberry-pi\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/picockpit.com\/raspberry-pi\/#\/schema\/logo\/image\/","url":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2023\/07\/Screenshot-from-2023-07-24-15-01-24.png","contentUrl":"https:\/\/picockpit.com\/raspberry-pi\/wp-content\/uploads\/2023\/07\/Screenshot-from-2023-07-24-15-01-24.png","width":1165,"height":283,"caption":"PiCockpit.com"},"image":{"@id":"https:\/\/picockpit.com\/raspberry-pi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pi3gshop","https:\/\/x.com\/pi3g"]},{"@type":"Person","@id":"https:\/\/picockpit.com\/raspberry-pi\/#\/schema\/person\/7af3a7a8c999bc722029ef9ca9d78eee","name":"baie de framboise","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c10c423ceeff34163dd54a5472d6da17d71c0e360e0cf8cdb8847006372f216b?s=96&d=blank&r=g","caption":"raspi berry"},"description":"Je suis l\u00e0 pour r\u00e9pondre \u00e0 toutes vos questions sur le Raspberry Pi et j'aime partager de nouvelles id\u00e9es de projets pour le Raspberry Pi et donner des conseils rapides. Bien s\u00fbr, je vous aiderai aussi avec PiCockpit et comment rendre votre Raspberry Pi encore plus facile \u00e0 utiliser avec cette solution de surveillance pour Raspberry Pi :-)","sameAs":["https:\/\/picockpit.com"],"url":"https:\/\/picockpit.com\/raspberry-pi\/fr\/author\/raspi-berry\/"}]}},"_links":{"self":[{"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":34,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":5073,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/posts\/110\/revisions\/5073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/media\/111"}],"wp:attachment":[{"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/picockpit.com\/raspberry-pi\/fr\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}